{"id":114,"count":341,"description":"Aqu\u00ed presentamos nuestra gama actual de tarjetas chip pre-programadas.\nNuestra terapia con las tarjetas chip especiales surgi\u00f3 a ra\u00edz de las demandas de nuestros terapeutas y usuarios para facilitar un acceso r\u00e1pido para la aplicaci\u00f3n de la terapia de frecuencias dirigidas. \nNuestra base de datos se ampl\u00eda constantemente en respuesta a las solicitudes. \nNuestras tarjetas chip funcionan en los dispositivos BW21 Goldenstream (a partir de la versi\u00f3n V12B), BW2020, BW2021, VM, as\u00ed como en el dispositivo terap\u00e9utico BW77.\nAl hacer el pedido, aseg\u00farese de pedir la tarjeta chip indicada para su dispositivo: VM, BW o DL. Para mayor informaci\u00f3n sobre la asignaci\u00f3n correcta de las tarjetas con chip y los dispositivos de frecuencia correspondientes, puede acudir a las preguntas frecuentes (FAQ).","link":"https:\/\/www.steramedig.com\/es\/Producto-Categor\u00eda\/tarjetas-chip-es-2\/","name":"Tarjetas chip","slug":"tarjetas-chip-es-2","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_cat\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product?product_cat=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}