{"id":9653,"date":"2021-07-08T12:06:56","date_gmt":"2021-07-08T10:06:56","guid":{"rendered":"https:\/\/www.steramedig.com\/?post_type=product&#038;p=9653"},"modified":"2021-10-28T16:08:44","modified_gmt":"2021-10-28T14:08:44","slug":"025-clonors-v-1-0-tarjeta-chip-bw-vm","status":"publish","type":"product","link":"https:\/\/www.steramedig.com\/es\/produkt\/025-clonors-v-1-0-tarjeta-chip-bw-vm\/","title":{"rendered":"025 Clonors V 1.0 tarjeta chip &#8211; BW\/VM"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Debes acceder para ver \u00e9ste contenido. Por favor <a class=\"swpm-login-link\" href=\"https:\/\/www.steramedig.com\/membership-login\/?swpm_redirect_to=https%3A%2F%2Fwww.steramedig.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fproduct%2F9653\">Acceder<\/a>. \u00bfA\u00fan no eres miembro? <a href=\"https:\/\/www.steramedig.com\/membership-join\/\">\u00danete a nosotros<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Tarjeta chip BW\/VM con frecuencias seg\u00fan el Dr. Rastocny contra las sanguijuelas Clonorchis sinensis.<\/p>\n","protected":false},"featured_media":11779,"template":"","meta":[],"product_cat":[233,114],"product_tag":[],"class_list":{"0":"post-9653","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-steramedig-es","7":"product_cat-tarjeta-chip-bw-vm","8":"product_cat-tarjetas-chip-es-2","9":"product_shipping_class-tarjetas-chips","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-variable"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product\/9653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media\/11779"}],"wp:attachment":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media?parent=9653"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_cat?post=9653"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_tag?post=9653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}