{"id":14537,"date":"2022-04-11T11:14:34","date_gmt":"2022-04-11T09:14:34","guid":{"rendered":"https:\/\/www.steramedig.com\/?post_type=product&#038;p=14537"},"modified":"2022-04-11T11:24:41","modified_gmt":"2022-04-11T09:24:41","slug":"139-mites-1-0-tarjeta-chip-dl","status":"publish","type":"product","link":"https:\/\/www.steramedig.com\/es\/produkt\/139-mites-1-0-tarjeta-chip-dl\/","title":{"rendered":"139 Mites 1.0 Tarjeta chip &#8211; DL"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Debes acceder para ver \u00e9ste contenido. Por favor <a class=\"swpm-login-link\" href=\"https:\/\/www.steramedig.com\/membership-login\/?swpm_redirect_to=https%3A%2F%2Fwww.steramedig.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fproduct%2F14537\">Acceder<\/a>. \u00bfA\u00fan no eres miembro? <a href=\"https:\/\/www.steramedig.com\/membership-join\/\">\u00danete a nosotros<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Tarjeta chip DL con frecuencias seg\u00fan el Dr. Rastocny contra 4 especies de \u00e1caros.<\/p>\n","protected":false},"featured_media":14529,"template":"","meta":[],"product_cat":[100,229,231,114],"product_tag":[],"class_list":{"0":"post-14537","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-steramedig-es","7":"product_brand-steramedig","8":"product_cat-chipcards","9":"product_cat-chipcards-dl","10":"product_cat-tarjeta-chip-dl","11":"product_cat-tarjetas-chip-es-2","12":"product_shipping_class-chipcards","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"product-type-variable"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product\/14537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media\/14529"}],"wp:attachment":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media?parent=14537"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_cat?post=14537"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_tag?post=14537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}