{"id":13046,"date":"2021-11-08T15:12:56","date_gmt":"2021-11-08T14:12:56","guid":{"rendered":"https:\/\/www.steramedig.com\/?post_type=product&#038;p=13046"},"modified":"2021-11-08T15:14:51","modified_gmt":"2021-11-08T14:14:51","slug":"056-mollusc-v-1-0-tarjeta-chip-dl","status":"publish","type":"product","link":"https:\/\/www.steramedig.com\/es\/produkt\/056-mollusc-v-1-0-tarjeta-chip-dl\/","title":{"rendered":"056 Mollusc V 1.0 tarjeta chip &#8211; DL"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Debes acceder para ver \u00e9ste contenido. Por favor <a class=\"swpm-login-link\" href=\"https:\/\/www.steramedig.com\/membership-login\/?swpm_redirect_to=https%3A%2F%2Fwww.steramedig.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fproduct%2F13046\">Acceder<\/a>. \u00bfA\u00fan no eres miembro? <a href=\"https:\/\/www.steramedig.com\/membership-join\/\">\u00danete a nosotros<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Tarjeta chip DL con frecuencias seg\u00fan el Dr. Rastocny contra los virus del molusco contagioso.<\/p>\n","protected":false},"featured_media":10324,"template":"","meta":[],"product_cat":[231,114],"product_tag":[],"class_list":{"0":"post-13046","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-steramedig-es","7":"product_cat-tarjeta-chip-dl","8":"product_cat-tarjetas-chip-es-2","9":"product_shipping_class-tarjetas-chips","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-variable"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product\/13046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media\/10324"}],"wp:attachment":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media?parent=13046"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_cat?post=13046"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_tag?post=13046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}