{"id":12922,"date":"2021-11-08T11:43:43","date_gmt":"2021-11-08T10:43:43","guid":{"rendered":"https:\/\/www.steramedig.com\/?post_type=product&#038;p=12922"},"modified":"2021-11-08T11:46:37","modified_gmt":"2021-11-08T10:46:37","slug":"042-schisto-v-1-0-tarjeta-chip-dl","status":"publish","type":"product","link":"https:\/\/www.steramedig.com\/es\/produkt\/042-schisto-v-1-0-tarjeta-chip-dl\/","title":{"rendered":"042 Schisto V 1.0 tarjeta chip &#8211; DL"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Debes acceder para ver \u00e9ste contenido. Por favor <a class=\"swpm-login-link\" href=\"https:\/\/www.steramedig.com\/membership-login\/?swpm_redirect_to=https%3A%2F%2Fwww.steramedig.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fproduct%2F12922\">Acceder<\/a>. \u00bfA\u00fan no eres miembro? <a href=\"https:\/\/www.steramedig.com\/membership-join\/\">\u00danete a nosotros<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Tarjeta Chip DL con frecuencias seg\u00fan el Dr. Rastocny contra 5 par\u00e1sitos esquistosomas.<\/p>\n","protected":false},"featured_media":10296,"template":"","meta":[],"product_cat":[231,114],"product_tag":[],"class_list":{"0":"post-12922","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-steramedig-es","7":"product_cat-tarjeta-chip-dl","8":"product_cat-tarjetas-chip-es-2","9":"product_shipping_class-tarjetas-chips","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-variable"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product\/12922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media\/10296"}],"wp:attachment":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media?parent=12922"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_cat?post=12922"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_tag?post=12922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}