{"id":10901,"date":"2021-07-20T12:06:34","date_gmt":"2021-07-20T10:06:34","guid":{"rendered":"https:\/\/www.steramedig.com\/?post_type=product&#038;p=10901"},"modified":"2021-11-10T14:59:47","modified_gmt":"2021-11-10T13:59:47","slug":"085-tu-vir-3-v-1-0-tarjeta-chip-bw-vm","status":"publish","type":"product","link":"https:\/\/www.steramedig.com\/es\/produkt\/085-tu-vir-3-v-1-0-tarjeta-chip-bw-vm\/","title":{"rendered":"085 Tu-Vir-3 V 1.0 tarjeta chip &#8211; BW\/VM"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Debes acceder para ver \u00e9ste contenido. Por favor <a class=\"swpm-login-link\" href=\"https:\/\/www.steramedig.com\/membership-login\/?swpm_redirect_to=https%3A%2F%2Fwww.steramedig.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fproduct%2F10901\">Acceder<\/a>. \u00bfA\u00fan no eres miembro? <a href=\"https:\/\/www.steramedig.com\/membership-join\/\">\u00danete a nosotros<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Tarjeta chip BW\/VM con las frecuencias seg\u00fan el Dr. Rastocny contra 2 virus tumorales.<\/p>\n","protected":false},"featured_media":10383,"template":"","meta":[],"product_cat":[233,114],"product_tag":[],"class_list":{"0":"post-10901","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-steramedig-es","7":"product_cat-tarjeta-chip-bw-vm","8":"product_cat-tarjetas-chip-es-2","9":"product_shipping_class-tarjetas-chips","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-variable"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product\/10901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media\/10383"}],"wp:attachment":[{"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/media?parent=10901"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_cat?post=10901"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.steramedig.com\/es\/wp-json\/wp\/v2\/product_tag?post=10901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}